{"id":9742,"date":"2023-02-03T09:26:56","date_gmt":"2023-02-03T09:26:56","guid":{"rendered":"https:\/\/fecburgos.com\/?p=9742"},"modified":"2023-02-03T11:42:45","modified_gmt":"2023-02-03T11:42:45","slug":"los-bonos-a-la-lectura-estan-de-vuelta","status":"publish","type":"post","link":"https:\/\/fecburgos.com\/index.php\/archivos\/9742","title":{"rendered":"\u00a1Los bonos a la lectura est\u00e1n de vuelta!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9742\" class=\"elementor elementor-9742\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24ef753c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24ef753c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e745e3\" data-id=\"6e745e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-736ebbe0 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"736ebbe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\" data-hamburger-icon=\"\" data-hamburger-icon-type=\"icon\" data-responsive-breakpoint=\"1024\">\n\t\t\t        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c0c4e8b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c0c4e8b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-24586078\" data-id=\"24586078\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2400aebb elementor-widget elementor-widget-image\" data-id=\"2400aebb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fecburgos.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"319\" height=\"218\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/LogoFECnuevo.gif\" class=\"attachment-large size-large wp-image-9\" alt=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a7ca3c6\" data-id=\"6a7ca3c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-595c7f17 elementor-widget elementor-widget-text-editor\" data-id=\"595c7f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Federaci\u00f3n de Empresarios de Comercio de Burgos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1315e86 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"1315e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\" data-hamburger-icon=\"fas fa-align-justify\" data-hamburger-icon-type=\"icon\" data-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\" type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon fas fa-align-justify\"><\/i>            <\/button>\n            <div role=\"navigation\" id=\"ekit-megamenu-principal\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-principal\" class=\"elementskit-navbar-nav elementskit-menu-po-left submenu-click-on-icon\"><li id=\"menu-item-14247\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14247 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/conocenos\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Con\u00f3cenos<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14272\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14272 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organigrama\" class=\" dropdown-item\">Organigrama<\/a>\t<\/li><li id=\"menu-item-14245\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14245 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/colaboradores\" class=\" dropdown-item\">Colaboradores<\/a>\t<\/li><li id=\"menu-item-14273\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14273 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organos-instituciones\" class=\" dropdown-item\">\u00d3rganos institucionales<\/a>\t<\/li><li id=\"menu-item-14282\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14282 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/responsabilidad-social\" class=\" dropdown-item\">Responsabilidad social<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14488\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14488 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestras-asociaciones\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestras asociaciones<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-17902\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17902 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-sectoriales-2\" class=\" dropdown-item\">Asociaciones Sectoriales<\/a>\t<\/li><li id=\"menu-item-14238\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14238 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-territoriales\" class=\" dropdown-item\">Asociaciones Territoriales<\/a>\t<\/li><li id=\"menu-item-14239\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14239 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-zonales\" class=\" dropdown-item\">Asociaciones Zonales<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15914\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15914 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestra-labor\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestra labor<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14253\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14253 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/formacion\" class=\" dropdown-item\">Formaci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14267\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14267 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/mobu-ediciones\" class=\" dropdown-item\">Mobu ediciones<\/a>\t<\/li><li id=\"menu-item-20812\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-20812 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/muestra-casa\" class=\" dropdown-item\">Muestra Casa<\/a>\t<\/li><li id=\"menu-item-21696\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21696 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/la-ubu-esta-de-moda\" class=\" dropdown-item\">La UBU est\u00e1 de MODA<\/a>\t<\/li><li id=\"menu-item-14278\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14278 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/premios-comercio-excelente\" class=\" dropdown-item\">Premios Comercio Excelente<\/a>\t<\/li><li id=\"menu-item-14254\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14254 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Foro Comercio<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-23053\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23053 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/xi-foro-comercio\" class=\" dropdown-item\">XI Foro Comercio<\/a>\t\t<\/li><li id=\"menu-item-21847\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21847 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Ediciones anteriores<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-14293 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"#\" class=\" dropdown-item\">Nuevas tecnolog\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14255\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14255 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/giscom\" class=\" dropdown-item\">Giscom<\/a>\t\t<\/li><li id=\"menu-item-14268\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14268 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/movilidad-comercial\" class=\" dropdown-item\">Movilidad Comercial<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14244\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14244 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/campana-de-promocion\" class=\" dropdown-item\">Campa\u00f1a de Promoci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14274\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14274 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/participaciones-y-colaboraciones\" class=\" dropdown-item\">Participaci\u00f3n y Colaboraci\u00f3n<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15137\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15137 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/informacion\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Informaci\u00f3n<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-15195\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15195 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Ventajas y Servicios<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-15292\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15292 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Asesoramiento<\/a>\t\t<\/li><li id=\"menu-item-15293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15293 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios#convenios\" class=\" dropdown-item\">Convenios<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14242\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14242 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/bolsa-de-empleo\" class=\" dropdown-item\">Empleo | Traspasos comerciales<\/a>\t<\/li><li id=\"menu-item-14250\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14250 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/convenios-colectivos\" class=\" dropdown-item\">Convenios Colectivos<\/a>\t<\/li><li id=\"menu-item-15139\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15139 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/normativa\" class=\" dropdown-item\">Normativa<\/a>\t<\/li><li id=\"menu-item-14261\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14261 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guias\" class=\" dropdown-item\">Gu\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14256\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14256 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-alimentacion\" class=\" dropdown-item\">Gu\u00eda alimentaci\u00f3n<\/a>\t\t<\/li><li id=\"menu-item-14257\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14257 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-de-la-persona\" class=\" dropdown-item\">Gu\u00eda Equipamiento de la Persona<\/a>\t\t<\/li><li id=\"menu-item-14258\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14258 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-del-hogar\" class=\" dropdown-item\">Gu\u00eda Equipamiento del Hogar<\/a>\t\t<\/li><li id=\"menu-item-14260\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14260 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-servicios-profesionales\" class=\" dropdown-item\">Gu\u00eda Servicios Profesionales<\/a>\t\t<\/li><li id=\"menu-item-14259\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14259 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-rrhh\" class=\" dropdown-item\">Gu\u00eda RRHH<\/a>\t\t<\/li><li id=\"menu-item-15152\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15152 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/GuiadeReformadeLocalesComerciales.pdf\" class=\" dropdown-item\">Gu\u00eda reforma de locales comerciales<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14252\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14252 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/diez-razones-para-asociarse\" class=\" dropdown-item\">Diez Razones para Asociarte<\/a>\t<\/li><li id=\"menu-item-15530\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15530 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2026\/02\/calendariolaboral2026.jpg\" class=\" dropdown-item\">Calendario laboral<\/a>\t<\/li><li id=\"menu-item-15531\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15531 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/CatalogoIntervencionesPrioritarias.pdf\" class=\" dropdown-item\">Cat\u00e1logo espacio urbano<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14241\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14241 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/blog\" class=\"ekit-menu-nav-link\">Blog<\/a><\/li>\n<li id=\"menu-item-14904\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14904 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociate\" class=\"ekit-menu-nav-link\">As\u00f3ciate<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eba024 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eba024\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a6b6a4c\" data-id=\"2a6b6a4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fa62731 elementor-widget elementor-widget-text-editor\" data-id=\"3fa62731\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a1Los bonos a la lectura est\u00e1n de vuelta!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cc40e70 elementor-widget elementor-widget-image\" data-id=\"3cc40e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"493\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO-1024x493.png\" class=\"attachment-large size-large wp-image-9745\" alt=\"\" srcset=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO-1024x493.png 1024w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO-300x145.png 300w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO-768x370.png 768w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO.png 1378w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77169a18 elementor-widget elementor-widget-text-editor\" data-id=\"77169a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con el claro objetivo de potenciar la lectura entre los m\u00e1s peque\u00f1os, el Ayuntamiento de Burgos ha puesto en marcha bonos de 24 euros para gastar en las librer\u00edas asociadas a la Asociaci\u00f3n Provincial de Libreros de Burgos.<\/p>\n<p><strong>Hasta el 3 de marzo<\/strong>, los alumnos de 3\u00ba de Primaria de los centros de la capital podr\u00e1n canjear estos bonos en los <strong>17 establecimientos adheridos a los Libreros de Burgos<\/strong>.<\/p>\n<p><strong>No son objetos de esta campa\u00f1a<\/strong> libros de texto, libros de referencia (diccionarios, atlas, etc.), literatura no infantil, papeler\u00eda, juegos, etc.<\/p>\n<p>Tambi\u00e9n es importante destacar que <strong>cada bono debe ser canjeado de manera \u00edntegra en una sola librer\u00eda<\/strong><\/p>\n<p>El Ayuntamiento va a destinar una partida de <strong>45.600 euros<\/strong> para esta iniciativa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de084f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de084f3\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-164e1b9b\" data-id=\"164e1b9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f26078f elementor-widget elementor-widget-text-editor\" data-id=\"6f26078f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Encu\u00e9ntranos en Burgos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b56d4d2 elementor-widget elementor-widget-html\" data-id=\"1b56d4d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" height=\"350\" src=\"https:\/\/maps.google.com\/maps?q=federaci%C3%B3n%20de%20comercio%20burgos&amp;t=m&amp;z=15&amp;output=embed&amp;iwloc=near\" aria-label=\"federaci\u00f3n de comercio burgos\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-662bf407\" data-id=\"662bf407\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4f9ede51\" data-id=\"4f9ede51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40f91779 elementor-widget elementor-widget-text-editor\" data-id=\"40f91779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Direcci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-224e1474 elementor-widget elementor-widget-text-editor\" data-id=\"224e1474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Av Castilla y Le\u00f3n 22 2\u00aa Planta<\/p><p>Burgos 09006<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e66ab7b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6e66ab7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1181376b elementor-widget elementor-widget-text-editor\" data-id=\"1181376b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contacto<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142c6f5f elementor-widget elementor-widget-text-editor\" data-id=\"142c6f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tel. 947 237 699<\/p><p>Email\u00a0 fec@fecburgos.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-486c66a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"486c66a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3df36912 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"3df36912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-fad8c24\" href=\"https:\/\/www.facebook.com\/federacioncomercioburgos\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-d0b82d1\" href=\"https:\/\/www.twitter.com\/FecBurgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f828413\" href=\"https:\/\/www.instagram.com\/fecburgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-92e68b7\" href=\"https:\/\/www.youtube.com\/channel\/UCG8Hz46O5uJDBQqgCJg8ChQ\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-25ab1acc\" data-id=\"25ab1acc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9542f84 elementor-widget elementor-widget-text-editor\" data-id=\"9542f84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00daltimas Noticias<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f005ee0 elementor-widget elementor-widget-html\" data-id=\"7f005ee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.facebook.com\/plugins\/page.php?href=https%3A%2F%2Fwww.facebook.com%2Ffederacioncomercioburgos%2F&amp;tabs=timeline&amp;width=340&amp;height=500&amp;small_header=false&amp;adapt_container_width=true&amp;hide_cover=false&amp;show_facepile=true&amp;appId=142539123146453\" width=\"340\" height=\"350\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ea21fbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ea21fbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-baaf0e6\" data-id=\"baaf0e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da7a753 elementor-widget elementor-widget-image\" data-id=\"da7a753\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.aytoburgos.es\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"124\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS-300x124.png\" class=\"attachment-medium size-medium wp-image-330\" alt=\"\" srcset=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS-300x124.png 300w, https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS-768x317.png 768w, https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS.png 851w\" sizes=\"(max-width: 300px) 100vw, 300px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1f40d9c8\" data-id=\"1f40d9c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c2ada33 elementor-widget elementor-widget-image\" data-id=\"3c2ada33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.jcyl.es\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"85\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/jcyl-fondo-blanco.png\" class=\"attachment-large size-large wp-image-1810\" alt=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-370f2a08\" data-id=\"370f2a08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7578cf2d\" data-id=\"7578cf2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a2d4e16 elementor-widget elementor-widget-text-editor\" data-id=\"2a2d4e16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a style=\"color:#8a8a8a\" href=\"http:\/\/fecburgos.com\/index.php\/aviso-legal\">Aviso Legal<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Con el claro objetivo de potenciar la lectura entre los m\u00e1s peque\u00f1os, el Ayuntamiento de Burgos ha puesto en marcha bonos de 24 euros para gastar en las librer\u00edas asociadas a la Asociaci\u00f3n Provincial de Libreros de Burgos.<\/p>\n","protected":false},"author":1,"featured_media":9745,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_canvas","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[47,17,31,37,13,154],"class_list":["post-9742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-bonos","tag-burgos","tag-comercio","tag-comerciolocal","tag-fecburgos","tag-libros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>\u00a1Los bonos a la lectura est\u00e1n de vuelta! - FecBurgos<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/fecburgos.com\/index.php\/archivos\/9742\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u00a1Los bonos a la lectura est\u00e1n de vuelta! - FecBurgos\" \/>\r\n<meta property=\"og:description\" content=\"Con el claro objetivo de potenciar la lectura entre los m\u00e1s peque\u00f1os, el Ayuntamiento de Burgos ha puesto en marcha bonos de 24 euros para gastar en las librer\u00edas asociadas a la Asociaci\u00f3n Provincial de Libreros de Burgos.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/fecburgos.com\/index.php\/archivos\/9742\" \/>\r\n<meta property=\"og:site_name\" content=\"FecBurgos\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-02-03T09:26:56+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-02-03T11:42:45+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1378\" \/>\r\n\t<meta property=\"og:image:height\" content=\"664\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"comerbur\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comerbur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742\"},\"author\":{\"name\":\"comerbur\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/58415e04731d3b7826555683d6f88ed7\"},\"headline\":\"\u00a1Los bonos a la lectura est\u00e1n de vuelta!\",\"datePublished\":\"2023-02-03T09:26:56+00:00\",\"dateModified\":\"2023-02-03T11:42:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742\"},\"wordCount\":324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO.png\",\"keywords\":[\"bonos\",\"Burgos\",\"comercio\",\"comerciolocal\",\"fecburgos\",\"libros\"],\"articleSection\":[\"Noticia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742\",\"name\":\"\u00a1Los bonos a la lectura est\u00e1n de vuelta! - FecBurgos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO.png\",\"datePublished\":\"2023-02-03T09:26:56+00:00\",\"dateModified\":\"2023-02-03T11:42:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#primaryimage\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO.png\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO.png\",\"width\":1378,\"height\":664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9742#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fecburgos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Los bonos a la lectura est\u00e1n de vuelta!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"name\":\"FecBurgos\",\"description\":\"Federaci\u00f3n de Empresarios de Comercio de Burgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fecburgos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\",\"name\":\"FecBurgos\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"width\":150,\"height\":135,\"caption\":\"FecBurgos\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/58415e04731d3b7826555683d6f88ed7\",\"name\":\"comerbur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"caption\":\"comerbur\"},\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/author\\\/comerbur\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Los bonos a la lectura est\u00e1n de vuelta! - FecBurgos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fecburgos.com\/index.php\/archivos\/9742","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Los bonos a la lectura est\u00e1n de vuelta! - FecBurgos","og_description":"Con el claro objetivo de potenciar la lectura entre los m\u00e1s peque\u00f1os, el Ayuntamiento de Burgos ha puesto en marcha bonos de 24 euros para gastar en las librer\u00edas asociadas a la Asociaci\u00f3n Provincial de Libreros de Burgos.","og_url":"https:\/\/fecburgos.com\/index.php\/archivos\/9742","og_site_name":"FecBurgos","article_published_time":"2023-02-03T09:26:56+00:00","article_modified_time":"2023-02-03T11:42:45+00:00","og_image":[{"width":1378,"height":664,"url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO.png","type":"image\/png"}],"author":"comerbur","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comerbur","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742#article","isPartOf":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742"},"author":{"name":"comerbur","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/58415e04731d3b7826555683d6f88ed7"},"headline":"\u00a1Los bonos a la lectura est\u00e1n de vuelta!","datePublished":"2023-02-03T09:26:56+00:00","dateModified":"2023-02-03T11:42:45+00:00","mainEntityOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742"},"wordCount":324,"commentCount":0,"publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO.png","keywords":["bonos","Burgos","comercio","comerciolocal","fecburgos","libros"],"articleSection":["Noticia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fecburgos.com\/index.php\/archivos\/9742#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742","url":"https:\/\/fecburgos.com\/index.php\/archivos\/9742","name":"\u00a1Los bonos a la lectura est\u00e1n de vuelta! - FecBurgos","isPartOf":{"@id":"https:\/\/fecburgos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742#primaryimage"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO.png","datePublished":"2023-02-03T09:26:56+00:00","dateModified":"2023-02-03T11:42:45+00:00","breadcrumb":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fecburgos.com\/index.php\/archivos\/9742"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742#primaryimage","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO.png","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/02\/LOGO.png","width":1378,"height":664},{"@type":"BreadcrumbList","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9742#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fecburgos.com\/"},{"@type":"ListItem","position":2,"name":"\u00a1Los bonos a la lectura est\u00e1n de vuelta!"}]},{"@type":"WebSite","@id":"https:\/\/fecburgos.com\/#website","url":"https:\/\/fecburgos.com\/","name":"FecBurgos","description":"Federaci\u00f3n de Empresarios de Comercio de Burgos","publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fecburgos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fecburgos.com\/#organization","name":"FecBurgos","url":"https:\/\/fecburgos.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","width":150,"height":135,"caption":"FecBurgos"},"image":{"@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/58415e04731d3b7826555683d6f88ed7","name":"comerbur","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","caption":"comerbur"},"url":"https:\/\/fecburgos.com\/index.php\/archivos\/author\/comerbur"}]}},"_links":{"self":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/9742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/comments?post=9742"}],"version-history":[{"count":10,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/9742\/revisions"}],"predecessor-version":[{"id":9794,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/9742\/revisions\/9794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media\/9745"}],"wp:attachment":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media?parent=9742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/categories?post=9742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/tags?post=9742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}