{"id":9532,"date":"2023-01-04T10:53:32","date_gmt":"2023-01-04T10:53:32","guid":{"rendered":"https:\/\/fecburgos.com\/?p=9532"},"modified":"2023-01-04T16:08:49","modified_gmt":"2023-01-04T16:08:49","slug":"la-feria-de-navidad-2022-cambia-de-emplazamiento-pero-mantiene-el-apoyo-de-los-burgaleses","status":"publish","type":"post","link":"https:\/\/fecburgos.com\/index.php\/archivos\/9532","title":{"rendered":"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9532\" class=\"elementor elementor-9532\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-386d1336 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"386d1336\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3419f323\" data-id=\"3419f323\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-707ac4a3 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"707ac4a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\" data-hamburger-icon=\"\" data-hamburger-icon-type=\"icon\" data-responsive-breakpoint=\"1024\">\n\t\t\t        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e98fe27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e98fe27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1dc19ad7\" data-id=\"1dc19ad7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b8201ba elementor-widget elementor-widget-image\" data-id=\"1b8201ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fecburgos.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"319\" height=\"218\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/LogoFECnuevo.gif\" class=\"attachment-large size-large wp-image-9\" alt=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61709176\" data-id=\"61709176\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a05917f elementor-widget elementor-widget-text-editor\" data-id=\"3a05917f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Federaci\u00f3n de Empresarios de Comercio de Burgos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a7143a8 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"2a7143a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\" data-hamburger-icon=\"fas fa-align-justify\" data-hamburger-icon-type=\"icon\" data-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\" type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon fas fa-align-justify\"><\/i>            <\/button>\n            <div role=\"navigation\" id=\"ekit-megamenu-principal\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-principal\" class=\"elementskit-navbar-nav elementskit-menu-po-left submenu-click-on-icon\"><li id=\"menu-item-14247\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14247 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/conocenos\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Con\u00f3cenos<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14272\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14272 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organigrama\" class=\" dropdown-item\">Organigrama<\/a>\t<\/li><li id=\"menu-item-14245\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14245 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/colaboradores\" class=\" dropdown-item\">Colaboradores<\/a>\t<\/li><li id=\"menu-item-14273\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14273 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organos-instituciones\" class=\" dropdown-item\">\u00d3rganos institucionales<\/a>\t<\/li><li id=\"menu-item-14282\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14282 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/responsabilidad-social\" class=\" dropdown-item\">Responsabilidad social<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14488\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14488 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestras-asociaciones\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestras asociaciones<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-17902\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17902 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-sectoriales-2\" class=\" dropdown-item\">Asociaciones Sectoriales<\/a>\t<\/li><li id=\"menu-item-14238\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14238 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-territoriales\" class=\" dropdown-item\">Asociaciones Territoriales<\/a>\t<\/li><li id=\"menu-item-14239\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14239 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-zonales\" class=\" dropdown-item\">Asociaciones Zonales<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15914\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15914 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestra-labor\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestra labor<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14253\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14253 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/formacion\" class=\" dropdown-item\">Formaci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14267\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14267 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/mobu-ediciones\" class=\" dropdown-item\">Mobu ediciones<\/a>\t<\/li><li id=\"menu-item-20812\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-20812 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/muestra-casa\" class=\" dropdown-item\">Muestra Casa<\/a>\t<\/li><li id=\"menu-item-21696\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21696 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/la-ubu-esta-de-moda\" class=\" dropdown-item\">La UBU est\u00e1 de MODA<\/a>\t<\/li><li id=\"menu-item-14278\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14278 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/premios-comercio-excelente\" class=\" dropdown-item\">Premios Comercio Excelente<\/a>\t<\/li><li id=\"menu-item-14254\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14254 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Foro Comercio<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-23053\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23053 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/xi-foro-comercio\" class=\" dropdown-item\">XI Foro Comercio<\/a>\t\t<\/li><li id=\"menu-item-21847\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21847 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Ediciones anteriores<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-14293 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"#\" class=\" dropdown-item\">Nuevas tecnolog\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14255\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14255 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/giscom\" class=\" dropdown-item\">Giscom<\/a>\t\t<\/li><li id=\"menu-item-14268\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14268 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/movilidad-comercial\" class=\" dropdown-item\">Movilidad Comercial<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14244\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14244 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/campana-de-promocion\" class=\" dropdown-item\">Campa\u00f1a de Promoci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14274\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14274 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/participaciones-y-colaboraciones\" class=\" dropdown-item\">Participaci\u00f3n y Colaboraci\u00f3n<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15137\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15137 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/informacion\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Informaci\u00f3n<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-15195\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15195 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Ventajas y Servicios<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-15292\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15292 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Asesoramiento<\/a>\t\t<\/li><li id=\"menu-item-15293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15293 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios#convenios\" class=\" dropdown-item\">Convenios<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14242\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14242 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/bolsa-de-empleo\" class=\" dropdown-item\">Empleo | Traspasos comerciales<\/a>\t<\/li><li id=\"menu-item-14250\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14250 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/convenios-colectivos\" class=\" dropdown-item\">Convenios Colectivos<\/a>\t<\/li><li id=\"menu-item-15139\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15139 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/normativa\" class=\" dropdown-item\">Normativa<\/a>\t<\/li><li id=\"menu-item-14261\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14261 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guias\" class=\" dropdown-item\">Gu\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14256\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14256 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-alimentacion\" class=\" dropdown-item\">Gu\u00eda alimentaci\u00f3n<\/a>\t\t<\/li><li id=\"menu-item-14257\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14257 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-de-la-persona\" class=\" dropdown-item\">Gu\u00eda Equipamiento de la Persona<\/a>\t\t<\/li><li id=\"menu-item-14258\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14258 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-del-hogar\" class=\" dropdown-item\">Gu\u00eda Equipamiento del Hogar<\/a>\t\t<\/li><li id=\"menu-item-14260\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14260 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-servicios-profesionales\" class=\" dropdown-item\">Gu\u00eda Servicios Profesionales<\/a>\t\t<\/li><li id=\"menu-item-14259\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14259 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-rrhh\" class=\" dropdown-item\">Gu\u00eda RRHH<\/a>\t\t<\/li><li id=\"menu-item-15152\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15152 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/GuiadeReformadeLocalesComerciales.pdf\" class=\" dropdown-item\">Gu\u00eda reforma de locales comerciales<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14252\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14252 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/diez-razones-para-asociarse\" class=\" dropdown-item\">Diez Razones para Asociarte<\/a>\t<\/li><li id=\"menu-item-15530\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15530 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2026\/02\/calendariolaboral2026.jpg\" class=\" dropdown-item\">Calendario laboral<\/a>\t<\/li><li id=\"menu-item-15531\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15531 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/CatalogoIntervencionesPrioritarias.pdf\" class=\" dropdown-item\">Cat\u00e1logo espacio urbano<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14241\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14241 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/blog\" class=\"ekit-menu-nav-link\">Blog<\/a><\/li>\n<li id=\"menu-item-14904\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14904 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociate\" class=\"ekit-menu-nav-link\">As\u00f3ciate<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55caac2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55caac2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60401bda\" data-id=\"60401bda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24074248 elementor-widget elementor-widget-text-editor\" data-id=\"24074248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59bd30a6 elementor-widget elementor-widget-image\" data-id=\"59bd30a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-1024x768.jpeg\" class=\"attachment-large size-large wp-image-9535\" alt=\"\" srcset=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-1024x768.jpeg 1024w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-300x225.jpeg 300w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-768x576.jpeg 768w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-1536x1152.jpeg 1536w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-2048x1536.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f3c1f6 elementor-widget elementor-widget-text-editor\" data-id=\"25f3c1f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con el comienzo de la Navidad, ya se ha vuelto tradici\u00f3n que se instale en Burgos la Feria de Navidad de los Floristas de Burgos (<a href=\"https:\/\/www.instagram.com\/fiestadelasflores\/\">FLOJABUR<\/a>) y este a\u00f1o no iba a ser menos. Ubicada en el F\u00f3rum Evoluci\u00f3n Burgos, esta Feria se ha consolidado como parte del programa navide\u00f1o de la ciudad, permitiendo que los visitantes pudiesen conocer las nuevas tendencias en decoraci\u00f3n navide\u00f1a y realizar, en consonancia a esas propuestas, las compras de art\u00edculos para estas fiestas.<\/p><p>Desde el 6 al 11 de diciembre se pudo disfrutar de este evento organizado por FLOJABUR la Asociaci\u00f3n Floristas de Burgos, que han mostrado sus art\u00edculos navide\u00f1os en los puestos instalados para la venta: Cultura de Flor, Coquelicot Flores, Regalos Jimena y Jardib\u00e9rica.<\/p><p>Tanto la nueva ubicaci\u00f3n como el aumento de los d\u00edas de duraci\u00f3n de la feria, fueron las novedades incorporadas y que obtuvieron una buena acogida por parte de los asistentes, ya que el F\u00f3rum Evoluci\u00f3n se consider\u00f3 un espacio \u00f3ptimo para su desarrollo al igual que la ampliaci\u00f3n de fechas del evento, que pas\u00f3 de 3 d\u00edas a 6, permitiendo visitar este mercado a un mayor n\u00famero de asistentes.<\/p><p>Adem\u00e1s de estas novedades, esta feria 2022 cont\u00f3 con la presencia de Pap\u00e1 Noel, que dedic\u00f3 especial atenci\u00f3n a los m\u00e1s peque\u00f1os de la casa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ebdbf56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ebdbf56\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ead4e1d\" data-id=\"ead4e1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a86f457 elementor-widget elementor-widget-text-editor\" data-id=\"7a86f457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Encu\u00e9ntranos en Burgos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-153d6a77 elementor-widget elementor-widget-html\" data-id=\"153d6a77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" height=\"350\" src=\"https:\/\/maps.google.com\/maps?q=federaci%C3%B3n%20de%20comercio%20burgos&amp;t=m&amp;z=15&amp;output=embed&amp;iwloc=near\" aria-label=\"federaci\u00f3n de comercio burgos\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5d979b02\" data-id=\"5d979b02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-62f7c12e\" data-id=\"62f7c12e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1102c3bd elementor-widget elementor-widget-text-editor\" data-id=\"1102c3bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Direcci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7164b1c1 elementor-widget elementor-widget-text-editor\" data-id=\"7164b1c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Av Castilla y Le\u00f3n 22 2\u00aa Planta<\/p><p>Burgos 09006<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20d2fd07 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"20d2fd07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-300ad812 elementor-widget elementor-widget-text-editor\" data-id=\"300ad812\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contacto<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75783283 elementor-widget elementor-widget-text-editor\" data-id=\"75783283\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tel. 947 237 699<\/p><p>Email\u00a0 fec@fecburgos.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c25280b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6c25280b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eb3609d elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"4eb3609d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-fad8c24\" href=\"https:\/\/www.facebook.com\/federacioncomercioburgos\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-d0b82d1\" href=\"https:\/\/www.twitter.com\/FecBurgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f828413\" href=\"https:\/\/www.instagram.com\/fecburgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-92e68b7\" href=\"https:\/\/www.youtube.com\/channel\/UCG8Hz46O5uJDBQqgCJg8ChQ\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5e70e332\" data-id=\"5e70e332\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb94fef elementor-widget elementor-widget-text-editor\" data-id=\"5eb94fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00daltimas Noticias<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59d9eb1f elementor-widget elementor-widget-html\" data-id=\"59d9eb1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.facebook.com\/plugins\/page.php?href=https%3A%2F%2Fwww.facebook.com%2Ffederacioncomercioburgos%2F&amp;tabs=timeline&amp;width=340&amp;height=500&amp;small_header=false&amp;adapt_container_width=true&amp;hide_cover=false&amp;show_facepile=true&amp;appId=142539123146453\" width=\"340\" height=\"350\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c107b5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c107b5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2e6d1df4\" data-id=\"2e6d1df4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-780c24ac elementor-widget elementor-widget-image\" data-id=\"780c24ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.aytoburgos.es\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"124\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS-300x124.png\" class=\"attachment-medium size-medium wp-image-330\" alt=\"\" srcset=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS-300x124.png 300w, https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS-768x317.png 768w, https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/AYUNTAMIENTO-BURGOS.png 851w\" sizes=\"(max-width: 300px) 100vw, 300px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-19d6b19a\" data-id=\"19d6b19a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14bfc8e7 elementor-widget elementor-widget-image\" data-id=\"14bfc8e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.jcyl.es\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"85\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/jcyl-fondo-blanco.png\" class=\"attachment-large size-large wp-image-1810\" alt=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cce6f9e\" data-id=\"cce6f9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-24a9cba7\" data-id=\"24a9cba7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b98c20c elementor-widget elementor-widget-text-editor\" data-id=\"2b98c20c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a style=\"color:#8a8a8a\" href=\"http:\/\/fecburgos.com\/index.php\/aviso-legal\">Aviso Legal<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Con el comienzo de la Navidad, ya se ha vuelto tradici\u00f3n que se instale en Burgos la Feria de Navidad de los Floristas de Burgos (FLOJABUR) y este a\u00f1o no iba a ser menos.<\/p>\n","protected":false},"author":1,"featured_media":9535,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_canvas","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[28,112,113,116,117,17,31,72,115,71,114,119,118],"class_list":["post-9532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evento","category-noticia","tag-navidad","tag-112","tag-adornos","tag-arbol","tag-belen","tag-burgos","tag-comercio","tag-feria","tag-floabur","tag-flores","tag-navideno","tag-papanoel","tag-reyesmagos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses - FecBurgos<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/fecburgos.com\/index.php\/archivos\/9532\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses - FecBurgos\" \/>\r\n<meta property=\"og:description\" content=\"Con el comienzo de la Navidad, ya se ha vuelto tradici\u00f3n que se instale en Burgos la Feria de Navidad de los Floristas de Burgos (FLOJABUR) y este a\u00f1o no iba a ser menos.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/fecburgos.com\/index.php\/archivos\/9532\" \/>\r\n<meta property=\"og:site_name\" content=\"FecBurgos\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-01-04T10:53:32+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-01-04T16:08:49+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-scaled.jpeg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"comerbur\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comerbur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532\"},\"author\":{\"name\":\"comerbur\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/58415e04731d3b7826555683d6f88ed7\"},\"headline\":\"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses\",\"datePublished\":\"2023-01-04T10:53:32+00:00\",\"dateModified\":\"2023-01-04T16:08:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/image00057-scaled.jpeg\",\"keywords\":[\"#navidad\",\"2022\",\"adornos\",\"arbol\",\"belen\",\"Burgos\",\"comercio\",\"Feria\",\"FLOABUR\",\"Flores\",\"navide\u00f1o\",\"papanoel\",\"reyesmagos\"],\"articleSection\":[\"Evento\",\"Noticia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532\",\"name\":\"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses - FecBurgos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/image00057-scaled.jpeg\",\"datePublished\":\"2023-01-04T10:53:32+00:00\",\"dateModified\":\"2023-01-04T16:08:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#primaryimage\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/image00057-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/image00057-scaled.jpeg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/9532#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fecburgos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"name\":\"FecBurgos\",\"description\":\"Federaci\u00f3n de Empresarios de Comercio de Burgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fecburgos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\",\"name\":\"FecBurgos\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"width\":150,\"height\":135,\"caption\":\"FecBurgos\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/58415e04731d3b7826555683d6f88ed7\",\"name\":\"comerbur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"caption\":\"comerbur\"},\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/author\\\/comerbur\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses - FecBurgos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fecburgos.com\/index.php\/archivos\/9532","og_locale":"es_ES","og_type":"article","og_title":"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses - FecBurgos","og_description":"Con el comienzo de la Navidad, ya se ha vuelto tradici\u00f3n que se instale en Burgos la Feria de Navidad de los Floristas de Burgos (FLOJABUR) y este a\u00f1o no iba a ser menos.","og_url":"https:\/\/fecburgos.com\/index.php\/archivos\/9532","og_site_name":"FecBurgos","article_published_time":"2023-01-04T10:53:32+00:00","article_modified_time":"2023-01-04T16:08:49+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-scaled.jpeg","type":"image\/jpeg"}],"author":"comerbur","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comerbur","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532#article","isPartOf":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532"},"author":{"name":"comerbur","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/58415e04731d3b7826555683d6f88ed7"},"headline":"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses","datePublished":"2023-01-04T10:53:32+00:00","dateModified":"2023-01-04T16:08:49+00:00","mainEntityOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-scaled.jpeg","keywords":["#navidad","2022","adornos","arbol","belen","Burgos","comercio","Feria","FLOABUR","Flores","navide\u00f1o","papanoel","reyesmagos"],"articleSection":["Evento","Noticia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fecburgos.com\/index.php\/archivos\/9532#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532","url":"https:\/\/fecburgos.com\/index.php\/archivos\/9532","name":"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses - FecBurgos","isPartOf":{"@id":"https:\/\/fecburgos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532#primaryimage"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-scaled.jpeg","datePublished":"2023-01-04T10:53:32+00:00","dateModified":"2023-01-04T16:08:49+00:00","breadcrumb":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fecburgos.com\/index.php\/archivos\/9532"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532#primaryimage","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-scaled.jpeg","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/01\/image00057-scaled.jpeg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/9532#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fecburgos.com\/"},{"@type":"ListItem","position":2,"name":"La Feria de Navidad 2022, cambia de emplazamiento y mantiene el apoyo de los burgaleses"}]},{"@type":"WebSite","@id":"https:\/\/fecburgos.com\/#website","url":"https:\/\/fecburgos.com\/","name":"FecBurgos","description":"Federaci\u00f3n de Empresarios de Comercio de Burgos","publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fecburgos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fecburgos.com\/#organization","name":"FecBurgos","url":"https:\/\/fecburgos.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","width":150,"height":135,"caption":"FecBurgos"},"image":{"@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/58415e04731d3b7826555683d6f88ed7","name":"comerbur","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","caption":"comerbur"},"url":"https:\/\/fecburgos.com\/index.php\/archivos\/author\/comerbur"}]}},"_links":{"self":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/9532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/comments?post=9532"}],"version-history":[{"count":11,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/9532\/revisions"}],"predecessor-version":[{"id":9595,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/9532\/revisions\/9595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media\/9535"}],"wp:attachment":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media?parent=9532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/categories?post=9532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/tags?post=9532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}