{"id":13612,"date":"2024-06-13T23:50:59","date_gmt":"2024-06-13T23:50:59","guid":{"rendered":"https:\/\/fecburgos.com\/?p=13612"},"modified":"2024-06-28T11:37:09","modified_gmt":"2024-06-28T11:37:09","slug":"psicologia-aplicada-a-la-venta","status":"publish","type":"post","link":"https:\/\/fecburgos.com\/index.php\/archivos\/13612","title":{"rendered":"Psicolog\u00eda aplicada a la venta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13612\" class=\"elementor elementor-13612\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8831ad elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f8831ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-316aa70\" data-id=\"316aa70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-328037f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"328037f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fecburgos.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"197\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/feclogoaltaresolucion-300x197.png\" class=\"attachment-medium size-medium wp-image-6539\" alt=\"\" srcset=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/feclogoaltaresolucion-300x197.png 300w, https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/feclogoaltaresolucion-1024x672.png 1024w, https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/feclogoaltaresolucion-768x504.png 768w, https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/feclogoaltaresolucion-1536x1008.png 1536w, https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/feclogoaltaresolucion-2048x1344.png 2048w, https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/elementor\/thumbs\/feclogoaltaresolucion-pavdqahq2i5kpjubspygh64udlcd66r20d74lpfsf4.png 75w, https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/elementor\/thumbs\/feclogoaltaresolucion-pavdqahq16shz3x1lfow9p8sk3655etbif0wogbisg.png 72w, https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/07\/elementor\/thumbs\/feclogoaltaresolucion-pavdqahq0b7rjds4kaoqxwpixlp9nx13d8vmjan876.png 70w\" sizes=\"(max-width: 300px) 100vw, 300px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d7798fa\" data-id=\"d7798fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b52aeea elementor-widget__width-initial elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"b52aeea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\" data-hamburger-icon=\"fas fa-align-justify\" data-hamburger-icon-type=\"icon\" data-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\" type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon fas fa-align-justify\"><\/i>            <\/button>\n            <div role=\"navigation\" id=\"ekit-megamenu-principal\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-principal\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-icon\"><li id=\"menu-item-14247\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14247 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/conocenos\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Con\u00f3cenos<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14272\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14272 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organigrama\" class=\" dropdown-item\">Organigrama<\/a>\t<\/li><li id=\"menu-item-14245\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14245 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/colaboradores\" class=\" dropdown-item\">Colaboradores<\/a>\t<\/li><li id=\"menu-item-14273\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14273 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organos-instituciones\" class=\" dropdown-item\">\u00d3rganos institucionales<\/a>\t<\/li><li id=\"menu-item-14282\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14282 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/responsabilidad-social\" class=\" dropdown-item\">Responsabilidad social<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14488\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14488 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestras-asociaciones\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestras asociaciones<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-17902\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17902 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-sectoriales-2\" class=\" dropdown-item\">Asociaciones Sectoriales<\/a>\t<\/li><li id=\"menu-item-14238\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14238 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-territoriales\" class=\" dropdown-item\">Asociaciones Territoriales<\/a>\t<\/li><li id=\"menu-item-14239\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14239 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-zonales\" class=\" dropdown-item\">Asociaciones Zonales<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15914\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15914 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestra-labor\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestra labor<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14253\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14253 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/formacion\" class=\" dropdown-item\">Formaci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14267\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14267 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/mobu-ediciones\" class=\" dropdown-item\">Mobu ediciones<\/a>\t<\/li><li id=\"menu-item-20812\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-20812 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/muestra-casa\" class=\" dropdown-item\">Muestra Casa<\/a>\t<\/li><li id=\"menu-item-21696\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21696 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/la-ubu-esta-de-moda\" class=\" dropdown-item\">La UBU est\u00e1 de MODA<\/a>\t<\/li><li id=\"menu-item-14278\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14278 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/premios-comercio-excelente\" class=\" dropdown-item\">Premios Comercio Excelente<\/a>\t<\/li><li id=\"menu-item-14254\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14254 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Foro Comercio<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-23053\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23053 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/xi-foro-comercio\" class=\" dropdown-item\">XI Foro Comercio<\/a>\t\t<\/li><li id=\"menu-item-21847\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21847 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Ediciones anteriores<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-14293 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"#\" class=\" dropdown-item\">Nuevas tecnolog\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14255\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14255 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/giscom\" class=\" dropdown-item\">Giscom<\/a>\t\t<\/li><li id=\"menu-item-14268\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14268 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/movilidad-comercial\" class=\" dropdown-item\">Movilidad Comercial<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14244\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14244 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/campana-de-promocion\" class=\" dropdown-item\">Campa\u00f1a de Promoci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14274\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14274 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/participaciones-y-colaboraciones\" class=\" dropdown-item\">Participaci\u00f3n y Colaboraci\u00f3n<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15137\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15137 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/informacion\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Informaci\u00f3n<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-15195\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15195 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Ventajas y Servicios<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-15292\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15292 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Asesoramiento<\/a>\t\t<\/li><li id=\"menu-item-15293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15293 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios#convenios\" class=\" dropdown-item\">Convenios<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14242\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14242 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/bolsa-de-empleo\" class=\" dropdown-item\">Empleo | Traspasos comerciales<\/a>\t<\/li><li id=\"menu-item-14250\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14250 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/convenios-colectivos\" class=\" dropdown-item\">Convenios Colectivos<\/a>\t<\/li><li id=\"menu-item-15139\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15139 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/normativa\" class=\" dropdown-item\">Normativa<\/a>\t<\/li><li id=\"menu-item-14261\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14261 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guias\" class=\" dropdown-item\">Gu\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14256\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14256 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-alimentacion\" class=\" dropdown-item\">Gu\u00eda alimentaci\u00f3n<\/a>\t\t<\/li><li id=\"menu-item-14257\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14257 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-de-la-persona\" class=\" dropdown-item\">Gu\u00eda Equipamiento de la Persona<\/a>\t\t<\/li><li id=\"menu-item-14258\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14258 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-del-hogar\" class=\" dropdown-item\">Gu\u00eda Equipamiento del Hogar<\/a>\t\t<\/li><li id=\"menu-item-14260\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14260 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-servicios-profesionales\" class=\" dropdown-item\">Gu\u00eda Servicios Profesionales<\/a>\t\t<\/li><li id=\"menu-item-14259\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14259 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-rrhh\" class=\" dropdown-item\">Gu\u00eda RRHH<\/a>\t\t<\/li><li id=\"menu-item-15152\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15152 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/GuiadeReformadeLocalesComerciales.pdf\" class=\" dropdown-item\">Gu\u00eda reforma de locales comerciales<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14252\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14252 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/diez-razones-para-asociarse\" class=\" dropdown-item\">Diez Razones para Asociarte<\/a>\t<\/li><li id=\"menu-item-15530\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15530 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2026\/02\/calendariolaboral2026.jpg\" class=\" dropdown-item\">Calendario laboral<\/a>\t<\/li><li id=\"menu-item-15531\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15531 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/CatalogoIntervencionesPrioritarias.pdf\" class=\" dropdown-item\">Cat\u00e1logo espacio urbano<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14241\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14241 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/blog\" class=\"ekit-menu-nav-link\">Blog<\/a><\/li>\n<li id=\"menu-item-14904\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14904 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociate\" class=\"ekit-menu-nav-link\">As\u00f3ciate<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06f6135 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06f6135\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a020708\" data-id=\"a020708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-388c9f3 elementor-widget elementor-widget-text-editor\" data-id=\"388c9f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Noticias de la FEC<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f96f2e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f96f2e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-591e4c99\" data-id=\"591e4c99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67040bda elementor-widget elementor-widget-text-editor\" data-id=\"67040bda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Taller: Psicolog\u00eda aplicada a la venta<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66238f89 elementor-widget elementor-widget-image\" data-id=\"66238f89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/elementor\/thumbs\/taller-idoia-qqbmx1cvywoo4az7baz8rrrqo1cy5dr1js4gf7bvrc.png\" title=\"taller idoia\" alt=\"taller idoia\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56cb3f4f elementor-widget elementor-widget-text-editor\" data-id=\"56cb3f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El martes 11 de junio, a las 14.30 a 17 horas tuvimos una nueva cita con la formaci\u00f3n.<\/p><p>Idoia Astui Garai, de la empresa Abent\u00e1jate (con b de beneficio), estuvo con nosotros para compartir su experiencia en la Psicolog\u00eda aplicada a la venta.<\/p><p>Contenido del taller:<\/p><ol><li>Conocer al cliente actual: Analizar el perfil del cliente actual, sus necesidades, preferencias y comportamientos de compra.<\/li><li>Entender los cambios en el proceso de compra: Identificar c\u00f3mo ha evolucionado el proceso de compra y qu\u00e9 factores influyen en la decisi\u00f3n de compra.<\/li><li>Comunicaci\u00f3n efectiva en ventas: Aprender t\u00e9cnicas de comunicaci\u00f3n efectiva para poder conectar con los clientes de forma m\u00e1s personalizada y efectiva.<\/li><li>Adaptaci\u00f3n del mensaje de ventas: Aprender a adaptar el mensaje de ventas a las necesidades y preferencias de los clientes actuales, enfoc\u00e1ndose en la personalizaci\u00f3n y la creaci\u00f3n de valor.<\/li><\/ol><p>Dada la hora prevista para la realizaci\u00f3n de la formaci\u00f3n, se ofreci\u00f3 un aperitivo a los asistentes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3116337 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"3116337\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\",\"stretch_section\":\"section-stretched\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15fc89e\" data-id=\"15fc89e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3bdb903 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3bdb903\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-416070d\" data-id=\"416070d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68fdfe2 elementor-widget elementor-widget-text-editor\" data-id=\"68fdfe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Encu\u00e9ntranos en Burgos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cce8f3c elementor-widget elementor-widget-html\" data-id=\"cce8f3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" height=\"350\" src=\"https:\/\/maps.google.com\/maps?q=federaci%C3%B3n%20de%20comercio%20burgos&amp;t=m&amp;z=15&amp;output=embed&amp;iwloc=near\" aria-label=\"federaci\u00f3n de comercio burgos\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bbcc3e3\" data-id=\"bbcc3e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c1d6bf elementor-widget elementor-widget-text-editor\" data-id=\"8c1d6bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Direcci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee439fb elementor-widget elementor-widget-text-editor\" data-id=\"ee439fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Av Castilla y Le\u00f3n 22 2\u00aa Planta<\/p><p>Burgos 09006<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0257aec elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0257aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c8896e elementor-widget elementor-widget-text-editor\" data-id=\"9c8896e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contacto<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76ce45d elementor-widget elementor-widget-text-editor\" data-id=\"76ce45d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tel. 947 237 699<\/p><p>Email\u00a0 fec@fecburgos.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df470e6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"df470e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa48b60 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"aa48b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-5347621\" href=\"https:\/\/www.facebook.com\/federacioncomercioburgos\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-x-twitter elementor-repeater-item-d0b82d1\" href=\"https:\/\/www.twitter.com\/FecBurgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">X-twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-x-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f828413\" href=\"https:\/\/www.instagram.com\/fecburgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-92e68b7\" href=\"https:\/\/www.youtube.com\/channel\/UCG8Hz46O5uJDBQqgCJg8ChQ\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-faf5e51\" data-id=\"faf5e51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb7f575 elementor-widget elementor-widget-text-editor\" data-id=\"fb7f575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00daltimas Noticias<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aba0ff5 elementor-widget elementor-widget-html\" data-id=\"aba0ff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.facebook.com\/plugins\/page.php?href=https%3A%2F%2Fwww.facebook.com%2Ffederacioncomercioburgos%2F&amp;tabs=timeline&amp;width=340&amp;height=500&amp;small_header=true&amp;adapt_container_width=true&amp;hide_cover=false&amp;show_facepile=true&amp;appId\" width=\"340\" height=\"350\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de959a5 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"de959a5\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"stretch_section\":\"section-stretched\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b048136\" data-id=\"b048136\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0775fcd\" data-id=\"0775fcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8766066 elementor-widget elementor-widget-image\" data-id=\"8766066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.aytoburgos.es\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2024\/06\/image-removebg-preview.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a1272c4\" data-id=\"a1272c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c9f32b elementor-widget elementor-widget-image\" data-id=\"7c9f32b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.jcyl.es\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"190\" height=\"85\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/jcyl-fondo-blanco.png\" class=\"attachment-medium size-medium wp-image-1810\" alt=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d6c5c61\" data-id=\"d6c5c61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcffca2 elementor-widget elementor-widget-text-editor\" data-id=\"bcffca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #ae9953;\" href=\"http:\/\/fecburgos.com\/index.php\/aviso-legal\">Aviso Legal<\/a>\u00a0 |\u00a0 <a style=\"color: #ae9953;\" href=\"https:\/\/fecburgos.com\/index.php\/politica-de-cookies\">Pol\u00edtica de cookies<\/a>\u00a0 |\u00a0 <a style=\"color: #ae9953;\" href=\"https:\/\/fecburgos.com\/index.php\/proteccion-datos\">Protecci\u00f3n de datos<\/a>\u00a0 |\u00a0 <a style=\"color: #ae9953;\" href=\"https:\/\/fecburgos.com\/index.php\/politica-de-privacidad\">Pol\u00edtica de privacidad<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4109f9 elementor-widget elementor-widget-text-editor\" data-id=\"a4109f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>@2024 todos los derechos reservados | IECOM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n de Empresarios de Comercio present\u00f3 el taller Psicolog\u00eda aplicada a la venta impartido por Idoia Astui de la empresa Abentajate.<\/p>\n","protected":false},"author":2,"featured_media":15735,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_canvas","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-13612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Psicolog\u00eda aplicada a la venta - FecBurgos<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/fecburgos.com\/index.php\/archivos\/13612\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Psicolog\u00eda aplicada a la venta - FecBurgos\" \/>\r\n<meta property=\"og:description\" content=\"La Federaci\u00f3n de Empresarios de Comercio present\u00f3 el taller Psicolog\u00eda aplicada a la venta impartido por Idoia Astui de la empresa Abentajate.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/fecburgos.com\/index.php\/archivos\/13612\" \/>\r\n<meta property=\"og:site_name\" content=\"FecBurgos\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-06-13T23:50:59+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-06-28T11:37:09+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2024\/06\/idoia.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"400\" \/>\r\n\t<meta property=\"og:image:height\" content=\"400\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"federaci\u00f3n\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"federaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612\"},\"author\":{\"name\":\"federaci\u00f3n\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/3fa21643986d38170f5f3c736c5e7b48\"},\"headline\":\"Psicolog\u00eda aplicada a la venta\",\"datePublished\":\"2024-06-13T23:50:59+00:00\",\"dateModified\":\"2024-06-28T11:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612\"},\"wordCount\":358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/idoia.png\",\"articleSection\":[\"Evento\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612\",\"name\":\"Psicolog\u00eda aplicada a la venta - FecBurgos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/idoia.png\",\"datePublished\":\"2024-06-13T23:50:59+00:00\",\"dateModified\":\"2024-06-28T11:37:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#primaryimage\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/idoia.png\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/idoia.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/13612#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fecburgos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Psicolog\u00eda aplicada a la venta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"name\":\"FecBurgos\",\"description\":\"Federaci\u00f3n de Empresarios de Comercio de Burgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fecburgos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\",\"name\":\"FecBurgos\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"width\":150,\"height\":135,\"caption\":\"FecBurgos\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/3fa21643986d38170f5f3c736c5e7b48\",\"name\":\"federaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f9fdc80c83e033e67583e6b78bdc860dd1d172179d0a663f1dc6fb814494876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f9fdc80c83e033e67583e6b78bdc860dd1d172179d0a663f1dc6fb814494876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f9fdc80c83e033e67583e6b78bdc860dd1d172179d0a663f1dc6fb814494876?s=96&d=mm&r=g\",\"caption\":\"federaci\u00f3n\"},\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/author\\\/burcomer\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Psicolog\u00eda aplicada a la venta - FecBurgos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fecburgos.com\/index.php\/archivos\/13612","og_locale":"es_ES","og_type":"article","og_title":"Psicolog\u00eda aplicada a la venta - FecBurgos","og_description":"La Federaci\u00f3n de Empresarios de Comercio present\u00f3 el taller Psicolog\u00eda aplicada a la venta impartido por Idoia Astui de la empresa Abentajate.","og_url":"https:\/\/fecburgos.com\/index.php\/archivos\/13612","og_site_name":"FecBurgos","article_published_time":"2024-06-13T23:50:59+00:00","article_modified_time":"2024-06-28T11:37:09+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2024\/06\/idoia.png","type":"image\/png"}],"author":"federaci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"federaci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612#article","isPartOf":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612"},"author":{"name":"federaci\u00f3n","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/3fa21643986d38170f5f3c736c5e7b48"},"headline":"Psicolog\u00eda aplicada a la venta","datePublished":"2024-06-13T23:50:59+00:00","dateModified":"2024-06-28T11:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612"},"wordCount":358,"commentCount":0,"publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2024\/06\/idoia.png","articleSection":["Evento"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fecburgos.com\/index.php\/archivos\/13612#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612","url":"https:\/\/fecburgos.com\/index.php\/archivos\/13612","name":"Psicolog\u00eda aplicada a la venta - FecBurgos","isPartOf":{"@id":"https:\/\/fecburgos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612#primaryimage"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2024\/06\/idoia.png","datePublished":"2024-06-13T23:50:59+00:00","dateModified":"2024-06-28T11:37:09+00:00","breadcrumb":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fecburgos.com\/index.php\/archivos\/13612"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612#primaryimage","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2024\/06\/idoia.png","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2024\/06\/idoia.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/13612#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fecburgos.com\/"},{"@type":"ListItem","position":2,"name":"Psicolog\u00eda aplicada a la venta"}]},{"@type":"WebSite","@id":"https:\/\/fecburgos.com\/#website","url":"https:\/\/fecburgos.com\/","name":"FecBurgos","description":"Federaci\u00f3n de Empresarios de Comercio de Burgos","publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fecburgos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fecburgos.com\/#organization","name":"FecBurgos","url":"https:\/\/fecburgos.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","width":150,"height":135,"caption":"FecBurgos"},"image":{"@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/3fa21643986d38170f5f3c736c5e7b48","name":"federaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2f9fdc80c83e033e67583e6b78bdc860dd1d172179d0a663f1dc6fb814494876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f9fdc80c83e033e67583e6b78bdc860dd1d172179d0a663f1dc6fb814494876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f9fdc80c83e033e67583e6b78bdc860dd1d172179d0a663f1dc6fb814494876?s=96&d=mm&r=g","caption":"federaci\u00f3n"},"url":"https:\/\/fecburgos.com\/index.php\/archivos\/author\/burcomer"}]}},"_links":{"self":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/13612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/comments?post=13612"}],"version-history":[{"count":53,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/13612\/revisions"}],"predecessor-version":[{"id":15738,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/13612\/revisions\/15738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media\/15735"}],"wp:attachment":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media?parent=13612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/categories?post=13612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/tags?post=13612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}