{"id":11572,"date":"2023-11-09T08:40:41","date_gmt":"2023-11-09T08:40:41","guid":{"rendered":"https:\/\/fecburgos.com\/?p=11572"},"modified":"2023-11-14T09:39:00","modified_gmt":"2023-11-14T09:39:00","slug":"fec-burgos-continua-impulsando-la-iniciativa-escuela-de-consumidores","status":"publish","type":"post","link":"https:\/\/fecburgos.com\/index.php\/archivos\/11572","title":{"rendered":"FEC Burgos continua impulsando la iniciativa \u00abEscuela de consumidores\u00bb"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11572\" class=\"elementor elementor-11572\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ff653c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ff653c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-449524ca\" data-id=\"449524ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6870a7c0 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"6870a7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\" data-hamburger-icon=\"\" data-hamburger-icon-type=\"icon\" data-responsive-breakpoint=\"1024\">\n\t\t\t        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d23b286 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d23b286\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a864478\" data-id=\"3a864478\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2539de13 elementor-widget elementor-widget-image\" data-id=\"2539de13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fecburgos.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"319\" height=\"218\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/LogoFECnuevo.gif\" class=\"attachment-large size-large wp-image-9\" alt=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-57cedf94\" data-id=\"57cedf94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17e67b26 elementor-widget elementor-widget-text-editor\" data-id=\"17e67b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Federaci\u00f3n de Empresarios de Comercio de Burgos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce49474 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"3ce49474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\" data-hamburger-icon=\"fas fa-align-justify\" data-hamburger-icon-type=\"icon\" data-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\" type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon fas fa-align-justify\"><\/i>            <\/button>\n            <div role=\"navigation\" id=\"ekit-megamenu-principal\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-principal\" class=\"elementskit-navbar-nav elementskit-menu-po-left submenu-click-on-icon\"><li id=\"menu-item-14247\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14247 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/conocenos\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Con\u00f3cenos<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14272\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14272 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organigrama\" class=\" dropdown-item\">Organigrama<\/a>\t<\/li><li id=\"menu-item-14245\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14245 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/colaboradores\" class=\" dropdown-item\">Colaboradores<\/a>\t<\/li><li id=\"menu-item-14273\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14273 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/organos-instituciones\" class=\" dropdown-item\">\u00d3rganos institucionales<\/a>\t<\/li><li id=\"menu-item-14282\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14282 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/responsabilidad-social\" class=\" dropdown-item\">Responsabilidad social<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14488\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14488 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestras-asociaciones\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestras asociaciones<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-17902\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17902 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-sectoriales-2\" class=\" dropdown-item\">Asociaciones Sectoriales<\/a>\t<\/li><li id=\"menu-item-14238\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14238 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-territoriales\" class=\" dropdown-item\">Asociaciones Territoriales<\/a>\t<\/li><li id=\"menu-item-14239\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14239 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociaciones-zonales\" class=\" dropdown-item\">Asociaciones Zonales<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15914\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15914 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/nuestra-labor\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Nuestra labor<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-14253\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14253 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/formacion\" class=\" dropdown-item\">Formaci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14267\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14267 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/mobu-ediciones\" class=\" dropdown-item\">Mobu ediciones<\/a>\t<\/li><li id=\"menu-item-20812\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-20812 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/muestra-casa\" class=\" dropdown-item\">Muestra Casa<\/a>\t<\/li><li id=\"menu-item-21696\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-21696 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/la-ubu-esta-de-moda\" class=\" dropdown-item\">La UBU est\u00e1 de MODA<\/a>\t<\/li><li id=\"menu-item-14278\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14278 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/premios-comercio-excelente\" class=\" dropdown-item\">Premios Comercio Excelente<\/a>\t<\/li><li id=\"menu-item-14254\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14254 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Foro Comercio<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-23053\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-23053 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/xi-foro-comercio\" class=\" dropdown-item\">XI Foro Comercio<\/a>\t\t<\/li><li id=\"menu-item-21847\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-21847 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/foro-comercio\" class=\" dropdown-item\">Ediciones anteriores<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-14293 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"#\" class=\" dropdown-item\">Nuevas tecnolog\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14255\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14255 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/giscom\" class=\" dropdown-item\">Giscom<\/a>\t\t<\/li><li id=\"menu-item-14268\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14268 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/movilidad-comercial\" class=\" dropdown-item\">Movilidad Comercial<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14244\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14244 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/campana-de-promocion\" class=\" dropdown-item\">Campa\u00f1a de Promoci\u00f3n<\/a>\t<\/li><li id=\"menu-item-14274\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14274 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/participaciones-y-colaboraciones\" class=\" dropdown-item\">Participaci\u00f3n y Colaboraci\u00f3n<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-15137\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15137 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/informacion\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Informaci\u00f3n<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-15195\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-15195 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Ventajas y Servicios<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-15292\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15292 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios\" class=\" dropdown-item\">Asesoramiento<\/a>\t\t<\/li><li id=\"menu-item-15293\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15293 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/ventajas-y-servicios#convenios\" class=\" dropdown-item\">Convenios<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14242\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14242 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/bolsa-de-empleo\" class=\" dropdown-item\">Empleo | Traspasos comerciales<\/a>\t<\/li><li id=\"menu-item-14250\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14250 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/convenios-colectivos\" class=\" dropdown-item\">Convenios Colectivos<\/a>\t<\/li><li id=\"menu-item-15139\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-15139 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/normativa\" class=\" dropdown-item\">Normativa<\/a>\t<\/li><li id=\"menu-item-14261\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-14261 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guias\" class=\" dropdown-item\">Gu\u00edas<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-14256\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14256 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-alimentacion\" class=\" dropdown-item\">Gu\u00eda alimentaci\u00f3n<\/a>\t\t<\/li><li id=\"menu-item-14257\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14257 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-de-la-persona\" class=\" dropdown-item\">Gu\u00eda Equipamiento de la Persona<\/a>\t\t<\/li><li id=\"menu-item-14258\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14258 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-equipamiento-del-hogar\" class=\" dropdown-item\">Gu\u00eda Equipamiento del Hogar<\/a>\t\t<\/li><li id=\"menu-item-14260\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14260 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-servicios-profesionales\" class=\" dropdown-item\">Gu\u00eda Servicios Profesionales<\/a>\t\t<\/li><li id=\"menu-item-14259\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14259 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/guia-rrhh\" class=\" dropdown-item\">Gu\u00eda RRHH<\/a>\t\t<\/li><li id=\"menu-item-15152\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15152 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/GuiadeReformadeLocalesComerciales.pdf\" class=\" dropdown-item\">Gu\u00eda reforma de locales comerciales<\/a>\t<\/li><\/ul>\n\t<\/li><li id=\"menu-item-14252\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14252 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/diez-razones-para-asociarse\" class=\" dropdown-item\">Diez Razones para Asociarte<\/a>\t<\/li><li id=\"menu-item-15530\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15530 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2026\/02\/calendariolaboral2026.jpg\" class=\" dropdown-item\">Calendario laboral<\/a>\t<\/li><li id=\"menu-item-15531\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-15531 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2021\/05\/CatalogoIntervencionesPrioritarias.pdf\" class=\" dropdown-item\">Cat\u00e1logo espacio urbano<\/a><\/li><\/ul>\n<\/li>\n<li id=\"menu-item-14241\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14241 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/blog\" class=\"ekit-menu-nav-link\">Blog<\/a><\/li>\n<li id=\"menu-item-14904\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-14904 nav-item elementskit-mobile-builder-content\" data-vertical-menu=\"750px\"><a href=\"https:\/\/fecburgos.com\/index.php\/asociate\" class=\"ekit-menu-nav-link\">As\u00f3ciate<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bcc5d0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bcc5d0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e7e6480\" data-id=\"3e7e6480\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3547bf65 elementor-widget elementor-widget-text-editor\" data-id=\"3547bf65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FEC Burgos continua impulsando la iniciativa \u00abEscuela de consumidores\u00bb<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1259d624 elementor-widget elementor-widget-image\" data-id=\"1259d624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg\" class=\"attachment-large size-large wp-image-11573\" alt=\"\" srcset=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg 1024w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386-300x225.jpg 300w, https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b1f4a7e elementor-widget elementor-widget-text-editor\" data-id=\"3b1f4a7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El 16 de octubre FEC Burgos acudi\u00f3 al CIFP Juan de Colonia en el marco de la actividad \u201cEscuela de Consumidores\u201d, proyecto desarrollado con la colaboraci\u00f3n del Ayuntamiento de Burgos, cuyo objetivo es reforzar la visibilidad y concienciar a los j\u00f3venes sobre la importancia del comercio local. En esta ocasi\u00f3n la protagonista fue Soraya Calvo, propietaria de la lencer\u00eda Celeste.<\/p><p>Los estudiantes del Grado en Medio de Actividades Comerciales y Grado Superior de Gesti\u00f3n de ventas y espacios comerciales del Juan de Colonia estuvieron presentes en esta charla en la que tambi\u00e9n se abord\u00f3 las iniciativas de emprendimiento en los m\u00e1s j\u00f3venes. Soraya subray\u00f3 la importancia del comercio local en el entramado econ\u00f3mico y social de la ciudad de Burgos. Adem\u00e1s, se\u00f1al\u00f3 las diversas oportunidades que ofrece este comercio en el \u00e1mbito laboral.<\/p><p>Dentro de este proyecto, tambi\u00e9n visitaron el pasado lunes 6 de noviembre las instalaciones de BigMat Fontecha, empresa burgalesa perteneciente al sector de materiales de construcci\u00f3n.<\/p><p>Consuelo Fontecha, gerente de BigMat Fontecha, fue la encargada de ense\u00f1ar las instalaciones y present\u00f3 al alumnado los diferentes perfiles profesionales presentes en la empresa. Tambi\u00e9n quiso se\u00f1alar la oportunidad laboral que ofrece el comercio local a los j\u00f3venes, invit\u00e1ndoles a que se acerquen y conozcan a las empresas locales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4190141d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4190141d\" data-element_type=\"section\" data-e-type=\"section\" data-settings='{\"background_background\":\"classic\"}'>\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-56f983ac\" data-id=\"56f983ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2de4407 elementor-widget elementor-widget-text-editor\" data-id=\"2de4407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Encu\u00e9ntranos en Burgos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f512b4e elementor-widget elementor-widget-html\" data-id=\"6f512b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" height=\"350\" src=\"https:\/\/maps.google.com\/maps?q=federaci%C3%B3n%20de%20comercio%20burgos&amp;t=m&amp;z=15&amp;output=embed&amp;iwloc=near\" aria-label=\"federaci\u00f3n de comercio burgos\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-592e57e2\" data-id=\"592e57e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1a6843c0\" data-id=\"1a6843c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d8c7a8b elementor-widget elementor-widget-text-editor\" data-id=\"4d8c7a8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Direcci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5a40a9 elementor-widget elementor-widget-text-editor\" data-id=\"3b5a40a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Av Castilla y Le\u00f3n 22 2\u00aa Planta<\/p><p>Burgos 09006<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-662bcccc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"662bcccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee5574b elementor-widget elementor-widget-text-editor\" data-id=\"4ee5574b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contacto<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e32fd4 elementor-widget elementor-widget-text-editor\" data-id=\"5e32fd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tel. 947 237 699<\/p><p>Email\u00a0 fec@fecburgos.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1586049d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1586049d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a52862c elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"5a52862c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-fad8c24\" href=\"https:\/\/www.facebook.com\/federacioncomercioburgos\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-d0b82d1\" href=\"https:\/\/www.twitter.com\/FecBurgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f828413\" href=\"https:\/\/www.instagram.com\/fecburgos\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-92e68b7\" href=\"https:\/\/www.youtube.com\/channel\/UCG8Hz46O5uJDBQqgCJg8ChQ\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8c00d17\" data-id=\"8c00d17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e3bac2f elementor-widget elementor-widget-text-editor\" data-id=\"5e3bac2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00daltimas Noticias<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b1e3437 elementor-widget elementor-widget-html\" data-id=\"1b1e3437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.facebook.com\/plugins\/page.php?href=https%3A%2F%2Fwww.facebook.com%2Ffederacioncomercioburgos%2F&amp;tabs=timeline&amp;width=340&amp;height=500&amp;small_header=false&amp;adapt_container_width=true&amp;hide_cover=false&amp;show_facepile=true&amp;appId=142539123146453\" width=\"340\" height=\"350\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowtransparency=\"true\" allow=\"encrypted-media\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d10e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d10e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-60b16965\" data-id=\"60b16965\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14508b1e elementor-widget elementor-widget-image\" data-id=\"14508b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.aytoburgos.es\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/Ayto_Agenda_Tras.png\" title=\"\" alt=\"\" loading=\"lazy\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-19378dd3\" data-id=\"19378dd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78536181 elementor-widget elementor-widget-image\" data-id=\"78536181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.jcyl.es\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"190\" height=\"85\" src=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/jcyl-fondo-blanco.png\" class=\"attachment-large size-large wp-image-1810\" alt=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6860c2ca\" data-id=\"6860c2ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17393e7 elementor-widget elementor-widget-text-editor\" data-id=\"17393e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a style=\"color:#8a8a8a\" href=\"http:\/\/fecburgos.com\/index.php\/aviso-legal\">Aviso Legal<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2537fc elementor-widget elementor-widget-text-editor\" data-id=\"e2537fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a style=\"color: #8a8a8a;\" href=\"https:\/\/fecburgos.com\/index.php\/politica-de-cookies\">Pol\u00edtica de cookies<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-608eef7b\" data-id=\"608eef7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71902483 elementor-widget elementor-widget-text-editor\" data-id=\"71902483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #8a8a8a;\" href=\"https:\/\/fecburgos.com\/index.php\/proteccion-datos\">Protecci\u00f3n de datos<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8cb226 elementor-widget elementor-widget-text-editor\" data-id=\"6c8cb226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #8a8a8a;\" href=\"https:\/\/fecburgos.com\/index.php\/politica-de-privacidad\">Pol\u00edtica de privacidad<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El 16 de octubre FEC Burgos acudi\u00f3 al CIFP Juan de Colonia en el marco de la actividad \u201cEscuela de Consumidores\u201d.<\/p>\n","protected":false},"author":1,"featured_media":11573,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_canvas","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[17,31,37,13],"class_list":["post-11572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evento","category-noticia","tag-burgos","tag-comercio","tag-comerciolocal","tag-fecburgos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>FEC Burgos continua impulsando la iniciativa &quot;Escuela de consumidores&quot; - FecBurgos<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/fecburgos.com\/index.php\/archivos\/11572\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"FEC Burgos continua impulsando la iniciativa &quot;Escuela de consumidores&quot; - FecBurgos\" \/>\r\n<meta property=\"og:description\" content=\"El 16 de octubre FEC Burgos acudi\u00f3 al CIFP Juan de Colonia en el marco de la actividad \u201cEscuela de Consumidores\u201d.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/fecburgos.com\/index.php\/archivos\/11572\" \/>\r\n<meta property=\"og:site_name\" content=\"FecBurgos\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-11-09T08:40:41+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-11-14T09:39:00+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\r\n\t<meta property=\"og:image:height\" content=\"768\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"comerbur\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comerbur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572\"},\"author\":{\"name\":\"comerbur\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/58415e04731d3b7826555683d6f88ed7\"},\"headline\":\"FEC Burgos continua impulsando la iniciativa \u00abEscuela de consumidores\u00bb\",\"datePublished\":\"2023-11-09T08:40:41+00:00\",\"dateModified\":\"2023-11-14T09:39:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg\",\"keywords\":[\"Burgos\",\"comercio\",\"comerciolocal\",\"fecburgos\"],\"articleSection\":[\"Evento\",\"Noticia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572\",\"name\":\"FEC Burgos continua impulsando la iniciativa \\\"Escuela de consumidores\\\" - FecBurgos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg\",\"datePublished\":\"2023-11-09T08:40:41+00:00\",\"dateModified\":\"2023-11-14T09:39:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#primaryimage\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/11572#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fecburgos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FEC Burgos continua impulsando la iniciativa \u00abEscuela de consumidores\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#website\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"name\":\"FecBurgos\",\"description\":\"Federaci\u00f3n de Empresarios de Comercio de Burgos\",\"publisher\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fecburgos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#organization\",\"name\":\"FecBurgos\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"contentUrl\":\"https:\\\/\\\/fecburgos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-cropped-LogoFEC-150x150-1.png\",\"width\":150,\"height\":135,\"caption\":\"FecBurgos\"},\"image\":{\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fecburgos.com\\\/#\\\/schema\\\/person\\\/58415e04731d3b7826555683d6f88ed7\",\"name\":\"comerbur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g\",\"caption\":\"comerbur\"},\"url\":\"https:\\\/\\\/fecburgos.com\\\/index.php\\\/archivos\\\/author\\\/comerbur\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FEC Burgos continua impulsando la iniciativa \"Escuela de consumidores\" - FecBurgos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fecburgos.com\/index.php\/archivos\/11572","og_locale":"es_ES","og_type":"article","og_title":"FEC Burgos continua impulsando la iniciativa \"Escuela de consumidores\" - FecBurgos","og_description":"El 16 de octubre FEC Burgos acudi\u00f3 al CIFP Juan de Colonia en el marco de la actividad \u201cEscuela de Consumidores\u201d.","og_url":"https:\/\/fecburgos.com\/index.php\/archivos\/11572","og_site_name":"FecBurgos","article_published_time":"2023-11-09T08:40:41+00:00","article_modified_time":"2023-11-14T09:39:00+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg","type":"image\/jpeg"}],"author":"comerbur","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comerbur","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572#article","isPartOf":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572"},"author":{"name":"comerbur","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/58415e04731d3b7826555683d6f88ed7"},"headline":"FEC Burgos continua impulsando la iniciativa \u00abEscuela de consumidores\u00bb","datePublished":"2023-11-09T08:40:41+00:00","dateModified":"2023-11-14T09:39:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg","keywords":["Burgos","comercio","comerciolocal","fecburgos"],"articleSection":["Evento","Noticia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fecburgos.com\/index.php\/archivos\/11572#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572","url":"https:\/\/fecburgos.com\/index.php\/archivos\/11572","name":"FEC Burgos continua impulsando la iniciativa \"Escuela de consumidores\" - FecBurgos","isPartOf":{"@id":"https:\/\/fecburgos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572#primaryimage"},"image":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572#primaryimage"},"thumbnailUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg","datePublished":"2023-11-09T08:40:41+00:00","dateModified":"2023-11-14T09:39:00+00:00","breadcrumb":{"@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fecburgos.com\/index.php\/archivos\/11572"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572#primaryimage","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2023\/11\/9aeb4b06-22d5-40ef-bdb1-bed7f73b2386.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/fecburgos.com\/index.php\/archivos\/11572#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fecburgos.com\/"},{"@type":"ListItem","position":2,"name":"FEC Burgos continua impulsando la iniciativa \u00abEscuela de consumidores\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/fecburgos.com\/#website","url":"https:\/\/fecburgos.com\/","name":"FecBurgos","description":"Federaci\u00f3n de Empresarios de Comercio de Burgos","publisher":{"@id":"https:\/\/fecburgos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fecburgos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fecburgos.com\/#organization","name":"FecBurgos","url":"https:\/\/fecburgos.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/","url":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","contentUrl":"https:\/\/fecburgos.com\/wp-content\/uploads\/2020\/05\/cropped-cropped-LogoFEC-150x150-1.png","width":150,"height":135,"caption":"FecBurgos"},"image":{"@id":"https:\/\/fecburgos.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fecburgos.com\/#\/schema\/person\/58415e04731d3b7826555683d6f88ed7","name":"comerbur","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ddbb4ace485868944ecba8fc1a806281a2ac4fe2123fa7322f60d7a68316d917?s=96&d=mm&r=g","caption":"comerbur"},"url":"https:\/\/fecburgos.com\/index.php\/archivos\/author\/comerbur"}]}},"_links":{"self":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/11572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/comments?post=11572"}],"version-history":[{"count":10,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/11572\/revisions"}],"predecessor-version":[{"id":11629,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/posts\/11572\/revisions\/11629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media\/11573"}],"wp:attachment":[{"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/media?parent=11572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/categories?post=11572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fecburgos.com\/index.php\/wp-json\/wp\/v2\/tags?post=11572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}